{"id":7840,"date":"2023-07-06T11:21:17","date_gmt":"2023-07-06T11:21:17","guid":{"rendered":"https:\/\/resales.e2visafranchises.com\/franchises\/e-2-visa-approved-reisebuchungs-franchise\/"},"modified":"2023-09-07T11:41:22","modified_gmt":"2023-09-07T11:41:22","slug":"e-2-visa-approved-reisebuchungs-franchise","status":"publish","type":"franchises","link":"https:\/\/resales.e2visafranchises.com\/de\/franchises\/e-2-visa-approved-reisebuchungs-franchise\/","title":{"rendered":"E-2 Visa Approved Reisebuchungs-Franchise"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vertrauensw\u00fcrdiges Franchise f\u00fcr die Buchung von Ferienunterk\u00fcnften<\/p>\n","protected":false},"author":11,"featured_media":7050,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","asking-price":"197000","_joinchat":[]},"price-range":[216],"industry":[248,364],"state":[384],"city":[868],"class_list":["post-7840","franchises","type-franchises","status-publish","has-post-thumbnail","hentry","price-range-100k-200k-de","industry-property-management-de","industry-travel-de","state-florida-de","city-anna-maria-island-de"],"_links":{"self":[{"href":"https:\/\/resales.e2visafranchises.com\/de\/wp-json\/wp\/v2\/franchises\/7840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resales.e2visafranchises.com\/de\/wp-json\/wp\/v2\/franchises"}],"about":[{"href":"https:\/\/resales.e2visafranchises.com\/de\/wp-json\/wp\/v2\/types\/franchises"}],"author":[{"embeddable":true,"href":"https:\/\/resales.e2visafranchises.com\/de\/wp-json\/wp\/v2\/users\/11"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resales.e2visafranchises.com\/de\/wp-json\/wp\/v2\/media\/7050"}],"wp:attachment":[{"href":"https:\/\/resales.e2visafranchises.com\/de\/wp-json\/wp\/v2\/media?parent=7840"}],"wp:term":[{"taxonomy":"price-range","embeddable":true,"href":"https:\/\/resales.e2visafranchises.com\/de\/wp-json\/wp\/v2\/price-range?post=7840"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/resales.e2visafranchises.com\/de\/wp-json\/wp\/v2\/industry?post=7840"},{"taxonomy":"state","embeddable":true,"href":"https:\/\/resales.e2visafranchises.com\/de\/wp-json\/wp\/v2\/state?post=7840"},{"taxonomy":"city","embeddable":true,"href":"https:\/\/resales.e2visafranchises.com\/de\/wp-json\/wp\/v2\/city?post=7840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}